{"id":345529,"date":"2026-01-26T15:53:19","date_gmt":"2026-01-26T13:53:19","guid":{"rendered":"https:\/\/mediagear.ee\/product\/blackmagic-design-cloud-store-max-48tb\/"},"modified":"2026-01-27T14:26:46","modified_gmt":"2026-01-27T12:26:46","slug":"blackmagic-design-cloud-store-max-48tb","status":"publish","type":"product","link":"https:\/\/mediagear.ee\/et\/toode\/blackmagic-design-cloud-store-max-48tb\/","title":{"rendered":"BLACKMAGIC DESIGN Cloud Store Max 48TB"},"content":{"rendered":"<p>Blackmagic Cloud Store Max is a new line of 1RU models of Cloud Store network storage. Cloud Store Max features extremely high performance flash storage, with 24 and 48TB models, 12 card RAID 0 flash memory core, 4x 10G Ethernet, 100G Ethernet, USB-C and Blackmagic Cloud sync for distributing files globally. <strong>Available from 5\/2024<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Blackmagic Cloud Store Max is a new line of 1RU models of Cloud Store network storage. Cloud Store Max features extremely high performance flash storage, with 24 and 48TB models, 12 card RAID 0 flash memory core, 4x 10G Ethernet, 100G Ethernet, USB-C and Blackmagic Cloud sync for distributing files globally. Available from 5\/2024.<\/p>\n","protected":false},"featured_media":345175,"template":"","meta":{"_acf_changed":false},"brand":[6848],"product_cat":[6667],"product_tag":[],"inventory":[],"class_list":["post-345529","product","type-product","status-publish","has-post-thumbnail","brand-blackmagic-design","product_cat-valised-kettaseadmed","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BLACKMAGIC DESIGN Cloud Store Max 48TB | MediaGear<\/title>\n<meta name=\"description\" content=\"Blackmagic Cloud Store Max is a new line of 1RU models of Cloud Store network storage. Cloud Store Max features extremely high performance flash st...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mediagear.ee\/et\/toode\/blackmagic-design-cloud-store-max-48tb\/\" \/>\n<meta property=\"og:locale\" content=\"et_EE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BLACKMAGIC DESIGN Cloud Store Max 48TB | MediaGear\" \/>\n<meta property=\"og:description\" content=\"Blackmagic Cloud Store Max is a new line of 1RU models of Cloud Store network storage. Cloud Store Max features extremely high performance flash st...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mediagear.ee\/et\/toode\/blackmagic-design-cloud-store-max-48tb\/\" \/>\n<meta property=\"og:site_name\" content=\"MediaGear\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Mediagear.ee\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-27T12:26:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mediagear.ee\/wp-content\/uploads\/2026\/01\/blackmagic-design-cloud-store-max-48tb-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mediagear.ee\\\/et\\\/toode\\\/blackmagic-design-cloud-store-max-48tb\\\/\",\"url\":\"https:\\\/\\\/mediagear.ee\\\/et\\\/toode\\\/blackmagic-design-cloud-store-max-48tb\\\/\",\"name\":\"BLACKMAGIC DESIGN Cloud Store Max 48TB | MediaGear\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mediagear.ee\\\/et\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mediagear.ee\\\/et\\\/toode\\\/blackmagic-design-cloud-store-max-48tb\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mediagear.ee\\\/et\\\/toode\\\/blackmagic-design-cloud-store-max-48tb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mediagear.ee\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/blackmagic-design-cloud-store-max-48tb-1.jpg\",\"datePublished\":\"2026-01-26T13:53:19+00:00\",\"dateModified\":\"2026-01-27T12:26:46+00:00\",\"description\":\"Blackmagic Cloud Store Max is a new line of 1RU models of Cloud Store network storage. Cloud Store Max features extremely high performance flash st...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mediagear.ee\\\/et\\\/toode\\\/blackmagic-design-cloud-store-max-48tb\\\/#breadcrumb\"},\"inLanguage\":\"et\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mediagear.ee\\\/et\\\/toode\\\/blackmagic-design-cloud-store-max-48tb\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"et\",\"@id\":\"https:\\\/\\\/mediagear.ee\\\/et\\\/toode\\\/blackmagic-design-cloud-store-max-48tb\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mediagear.ee\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/blackmagic-design-cloud-store-max-48tb-1.jpg\",\"contentUrl\":\"https:\\\/\\\/mediagear.ee\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/blackmagic-design-cloud-store-max-48tb-1.jpg\",\"width\":1200,\"height\":1200,\"caption\":\"BLACKMAGIC DESIGN Cloud Store Max 48TB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mediagear.ee\\\/et\\\/toode\\\/blackmagic-design-cloud-store-max-48tb\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Avaleht\",\"item\":\"https:\\\/\\\/mediagear.ee\\\/et\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pro video &amp; audio tehnika pood\",\"item\":\"https:\\\/\\\/mediagear.ee\\\/et\\\/pood\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SALVESTUSMEEDIA\",\"item\":\"https:\\\/\\\/mediagear.ee\\\/et\\\/tootekategooria\\\/salvestusmeedia\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"V\u00e4lised kettaseadmed\",\"item\":\"https:\\\/\\\/mediagear.ee\\\/et\\\/tootekategooria\\\/salvestusmeedia\\\/valised-kettaseadmed\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"BLACKMAGIC DESIGN Cloud Store Max 48TB\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mediagear.ee\\\/et\\\/#website\",\"url\":\"https:\\\/\\\/mediagear.ee\\\/et\\\/\",\"name\":\"MediaGear\",\"description\":\"Full-service solutions in AV equipment\",\"publisher\":{\"@id\":\"https:\\\/\\\/mediagear.ee\\\/et\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mediagear.ee\\\/et\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"et\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mediagear.ee\\\/et\\\/#organization\",\"name\":\"Mediagear\",\"url\":\"https:\\\/\\\/mediagear.ee\\\/et\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"et\",\"@id\":\"https:\\\/\\\/mediagear.ee\\\/et\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mediagear.ee\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/MediaGear-logo-transp.png\",\"contentUrl\":\"https:\\\/\\\/mediagear.ee\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/MediaGear-logo-transp.png\",\"width\":600,\"height\":200,\"caption\":\"Mediagear\"},\"image\":{\"@id\":\"https:\\\/\\\/mediagear.ee\\\/et\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Mediagear.ee\\\/\",\"https:\\\/\\\/www.instagram.com\\\/mediagear_ee\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BLACKMAGIC DESIGN Cloud Store Max 48TB | MediaGear","description":"Blackmagic Cloud Store Max is a new line of 1RU models of Cloud Store network storage. Cloud Store Max features extremely high performance flash st...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mediagear.ee\/et\/toode\/blackmagic-design-cloud-store-max-48tb\/","og_locale":"et_EE","og_type":"article","og_title":"BLACKMAGIC DESIGN Cloud Store Max 48TB | MediaGear","og_description":"Blackmagic Cloud Store Max is a new line of 1RU models of Cloud Store network storage. Cloud Store Max features extremely high performance flash st...","og_url":"https:\/\/mediagear.ee\/et\/toode\/blackmagic-design-cloud-store-max-48tb\/","og_site_name":"MediaGear","article_publisher":"https:\/\/www.facebook.com\/Mediagear.ee\/","article_modified_time":"2026-01-27T12:26:46+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/mediagear.ee\/wp-content\/uploads\/2026\/01\/blackmagic-design-cloud-store-max-48tb-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mediagear.ee\/et\/toode\/blackmagic-design-cloud-store-max-48tb\/","url":"https:\/\/mediagear.ee\/et\/toode\/blackmagic-design-cloud-store-max-48tb\/","name":"BLACKMAGIC DESIGN Cloud Store Max 48TB | MediaGear","isPartOf":{"@id":"https:\/\/mediagear.ee\/et\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mediagear.ee\/et\/toode\/blackmagic-design-cloud-store-max-48tb\/#primaryimage"},"image":{"@id":"https:\/\/mediagear.ee\/et\/toode\/blackmagic-design-cloud-store-max-48tb\/#primaryimage"},"thumbnailUrl":"https:\/\/mediagear.ee\/wp-content\/uploads\/2026\/01\/blackmagic-design-cloud-store-max-48tb-1.jpg","datePublished":"2026-01-26T13:53:19+00:00","dateModified":"2026-01-27T12:26:46+00:00","description":"Blackmagic Cloud Store Max is a new line of 1RU models of Cloud Store network storage. Cloud Store Max features extremely high performance flash st...","breadcrumb":{"@id":"https:\/\/mediagear.ee\/et\/toode\/blackmagic-design-cloud-store-max-48tb\/#breadcrumb"},"inLanguage":"et","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mediagear.ee\/et\/toode\/blackmagic-design-cloud-store-max-48tb\/"]}]},{"@type":"ImageObject","inLanguage":"et","@id":"https:\/\/mediagear.ee\/et\/toode\/blackmagic-design-cloud-store-max-48tb\/#primaryimage","url":"https:\/\/mediagear.ee\/wp-content\/uploads\/2026\/01\/blackmagic-design-cloud-store-max-48tb-1.jpg","contentUrl":"https:\/\/mediagear.ee\/wp-content\/uploads\/2026\/01\/blackmagic-design-cloud-store-max-48tb-1.jpg","width":1200,"height":1200,"caption":"BLACKMAGIC DESIGN Cloud Store Max 48TB"},{"@type":"BreadcrumbList","@id":"https:\/\/mediagear.ee\/et\/toode\/blackmagic-design-cloud-store-max-48tb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Avaleht","item":"https:\/\/mediagear.ee\/et\/"},{"@type":"ListItem","position":2,"name":"Pro video &amp; audio tehnika pood","item":"https:\/\/mediagear.ee\/et\/pood\/"},{"@type":"ListItem","position":3,"name":"SALVESTUSMEEDIA","item":"https:\/\/mediagear.ee\/et\/tootekategooria\/salvestusmeedia\/"},{"@type":"ListItem","position":4,"name":"V\u00e4lised kettaseadmed","item":"https:\/\/mediagear.ee\/et\/tootekategooria\/salvestusmeedia\/valised-kettaseadmed\/"},{"@type":"ListItem","position":5,"name":"BLACKMAGIC DESIGN Cloud Store Max 48TB"}]},{"@type":"WebSite","@id":"https:\/\/mediagear.ee\/et\/#website","url":"https:\/\/mediagear.ee\/et\/","name":"MediaGear","description":"Full-service solutions in AV equipment","publisher":{"@id":"https:\/\/mediagear.ee\/et\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mediagear.ee\/et\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"et"},{"@type":"Organization","@id":"https:\/\/mediagear.ee\/et\/#organization","name":"Mediagear","url":"https:\/\/mediagear.ee\/et\/","logo":{"@type":"ImageObject","inLanguage":"et","@id":"https:\/\/mediagear.ee\/et\/#\/schema\/logo\/image\/","url":"https:\/\/mediagear.ee\/wp-content\/uploads\/2024\/05\/MediaGear-logo-transp.png","contentUrl":"https:\/\/mediagear.ee\/wp-content\/uploads\/2024\/05\/MediaGear-logo-transp.png","width":600,"height":200,"caption":"Mediagear"},"image":{"@id":"https:\/\/mediagear.ee\/et\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Mediagear.ee\/","https:\/\/www.instagram.com\/mediagear_ee\/"]}]}},"_links":{"self":[{"href":"https:\/\/mediagear.ee\/et\/wp-json\/wp\/v2\/product\/345529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mediagear.ee\/et\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mediagear.ee\/et\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mediagear.ee\/et\/wp-json\/wp\/v2\/media\/345175"}],"wp:attachment":[{"href":"https:\/\/mediagear.ee\/et\/wp-json\/wp\/v2\/media?parent=345529"}],"wp:term":[{"taxonomy":"brand","embeddable":true,"href":"https:\/\/mediagear.ee\/et\/wp-json\/wp\/v2\/brand?post=345529"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mediagear.ee\/et\/wp-json\/wp\/v2\/product_cat?post=345529"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mediagear.ee\/et\/wp-json\/wp\/v2\/product_tag?post=345529"},{"taxonomy":"inventory","embeddable":true,"href":"https:\/\/mediagear.ee\/et\/wp-json\/wp\/v2\/inventory?post=345529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}