{"id":280228,"date":"2025-06-10T16:17:56","date_gmt":"2025-06-10T13:17:56","guid":{"rendered":"http:\/\/mediagear.ee\/product\/atomos-hdmi-2-0-micro-cable-30-60cm\/"},"modified":"2025-06-10T15:17:56","modified_gmt":"2025-06-10T13:17:56","slug":"atomos-hdmi-2-0-micro-cable-30-60cm","status":"publish","type":"product","link":"https:\/\/mediagear.ee\/fi\/tuote\/atomos-hdmi-2-0-micro-cable-30-60cm\/","title":{"rendered":"ATOMOS HDMI 2.0 Micro cable, 30\/60cm"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>30cm die cast connector (60cm extended)<br \/>\nHDMI 2.0 READY<br \/>\nPasses the high speed tests laid out in HDMI 2.0. 4Kp60 and HD 240p are fully supported.<br \/>\nHDR READY<br \/>\nCompatible with High Dynamic Range (HDR) product line up.<\/p>\n","protected":false},"featured_media":280229,"template":"","meta":{"_acf_changed":false},"brand":[5973],"product_cat":[6041],"product_tag":[],"inventory":[],"class_list":["post-280228","product","type-product","status-publish","has-post-thumbnail","brand-atomos-fi","product_cat-hdmi-cables-fi","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ATOMOS HDMI 2.0 Micro cable, 30\/60cm - MediaGear<\/title>\n<meta name=\"description\" content=\"30cm die cast connector (60cm extended) HDMI 2.0 READY Passes the high speed tests laid out in HDMI 2.0. 4Kp60 and HD 240p are fully supported. HDR...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mediagear.ee\/fi\/tuote\/atomos-hdmi-2-0-micro-cable-30-60cm\/\" \/>\n<meta property=\"og:locale\" content=\"fi_FI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ATOMOS HDMI 2.0 Micro cable, 30\/60cm - MediaGear\" \/>\n<meta property=\"og:description\" content=\"30cm die cast connector (60cm extended) HDMI 2.0 READY Passes the high speed tests laid out in HDMI 2.0. 4Kp60 and HD 240p are fully supported. HDR...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mediagear.ee\/fi\/tuote\/atomos-hdmi-2-0-micro-cable-30-60cm\/\" \/>\n<meta property=\"og:site_name\" content=\"MediaGear\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Mediagear.ee\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mediagear.ee\/wp-content\/uploads\/2025\/06\/p7566579_855488888_4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"534\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mediagear.ee\\\/fi\\\/tuote\\\/atomos-hdmi-2-0-micro-cable-30-60cm\\\/\",\"url\":\"https:\\\/\\\/mediagear.ee\\\/fi\\\/tuote\\\/atomos-hdmi-2-0-micro-cable-30-60cm\\\/\",\"name\":\"ATOMOS HDMI 2.0 Micro cable, 30\\\/60cm - MediaGear\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mediagear.ee\\\/fi\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mediagear.ee\\\/fi\\\/tuote\\\/atomos-hdmi-2-0-micro-cable-30-60cm\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mediagear.ee\\\/fi\\\/tuote\\\/atomos-hdmi-2-0-micro-cable-30-60cm\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mediagear.ee\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/p7566579_855488888_4.jpg\",\"datePublished\":\"2025-06-10T13:17:56+00:00\",\"description\":\"30cm die cast connector (60cm extended) HDMI 2.0 READY Passes the high speed tests laid out in HDMI 2.0. 4Kp60 and HD 240p are fully supported. HDR...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mediagear.ee\\\/fi\\\/tuote\\\/atomos-hdmi-2-0-micro-cable-30-60cm\\\/#breadcrumb\"},\"inLanguage\":\"fi\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mediagear.ee\\\/fi\\\/tuote\\\/atomos-hdmi-2-0-micro-cable-30-60cm\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fi\",\"@id\":\"https:\\\/\\\/mediagear.ee\\\/fi\\\/tuote\\\/atomos-hdmi-2-0-micro-cable-30-60cm\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mediagear.ee\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/p7566579_855488888_4.jpg\",\"contentUrl\":\"https:\\\/\\\/mediagear.ee\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/p7566579_855488888_4.jpg\",\"width\":800,\"height\":534,\"caption\":\"ATOMOS HDMI 2.0 Micro cable, 30\\\/60cm\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mediagear.ee\\\/fi\\\/tuote\\\/atomos-hdmi-2-0-micro-cable-30-60cm\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mediagear.ee\\\/fi\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pro video- ja \u00e4\u00e4nilaitteiden kauppa\",\"item\":\"https:\\\/\\\/mediagear.ee\\\/fi\\\/kauppa\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"KAAPELIT\",\"item\":\"https:\\\/\\\/mediagear.ee\\\/fi\\\/tuote-osasto\\\/cabling-fi\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"HDMI kaapelit\",\"item\":\"https:\\\/\\\/mediagear.ee\\\/fi\\\/tuote-osasto\\\/cabling-fi\\\/hdmi-cables-fi\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"ATOMOS HDMI 2.0 Micro cable, 30\\\/60cm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mediagear.ee\\\/fi\\\/#website\",\"url\":\"https:\\\/\\\/mediagear.ee\\\/fi\\\/\",\"name\":\"MediaGear\",\"description\":\"Full-service solutions in AV equipment\",\"publisher\":{\"@id\":\"https:\\\/\\\/mediagear.ee\\\/fi\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mediagear.ee\\\/fi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fi\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mediagear.ee\\\/fi\\\/#organization\",\"name\":\"Mediagear\",\"url\":\"https:\\\/\\\/mediagear.ee\\\/fi\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fi\",\"@id\":\"https:\\\/\\\/mediagear.ee\\\/fi\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mediagear.ee\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/MediaGear-logo-transp.png\",\"contentUrl\":\"https:\\\/\\\/mediagear.ee\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/MediaGear-logo-transp.png\",\"width\":600,\"height\":200,\"caption\":\"Mediagear\"},\"image\":{\"@id\":\"https:\\\/\\\/mediagear.ee\\\/fi\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Mediagear.ee\\\/\",\"https:\\\/\\\/www.instagram.com\\\/mediagear_ee\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ATOMOS HDMI 2.0 Micro cable, 30\/60cm - MediaGear","description":"30cm die cast connector (60cm extended) HDMI 2.0 READY Passes the high speed tests laid out in HDMI 2.0. 4Kp60 and HD 240p are fully supported. HDR...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mediagear.ee\/fi\/tuote\/atomos-hdmi-2-0-micro-cable-30-60cm\/","og_locale":"fi_FI","og_type":"article","og_title":"ATOMOS HDMI 2.0 Micro cable, 30\/60cm - MediaGear","og_description":"30cm die cast connector (60cm extended) HDMI 2.0 READY Passes the high speed tests laid out in HDMI 2.0. 4Kp60 and HD 240p are fully supported. HDR...","og_url":"https:\/\/mediagear.ee\/fi\/tuote\/atomos-hdmi-2-0-micro-cable-30-60cm\/","og_site_name":"MediaGear","article_publisher":"https:\/\/www.facebook.com\/Mediagear.ee\/","og_image":[{"width":800,"height":534,"url":"https:\/\/mediagear.ee\/wp-content\/uploads\/2025\/06\/p7566579_855488888_4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mediagear.ee\/fi\/tuote\/atomos-hdmi-2-0-micro-cable-30-60cm\/","url":"https:\/\/mediagear.ee\/fi\/tuote\/atomos-hdmi-2-0-micro-cable-30-60cm\/","name":"ATOMOS HDMI 2.0 Micro cable, 30\/60cm - MediaGear","isPartOf":{"@id":"https:\/\/mediagear.ee\/fi\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mediagear.ee\/fi\/tuote\/atomos-hdmi-2-0-micro-cable-30-60cm\/#primaryimage"},"image":{"@id":"https:\/\/mediagear.ee\/fi\/tuote\/atomos-hdmi-2-0-micro-cable-30-60cm\/#primaryimage"},"thumbnailUrl":"https:\/\/mediagear.ee\/wp-content\/uploads\/2025\/06\/p7566579_855488888_4.jpg","datePublished":"2025-06-10T13:17:56+00:00","description":"30cm die cast connector (60cm extended) HDMI 2.0 READY Passes the high speed tests laid out in HDMI 2.0. 4Kp60 and HD 240p are fully supported. HDR...","breadcrumb":{"@id":"https:\/\/mediagear.ee\/fi\/tuote\/atomos-hdmi-2-0-micro-cable-30-60cm\/#breadcrumb"},"inLanguage":"fi","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mediagear.ee\/fi\/tuote\/atomos-hdmi-2-0-micro-cable-30-60cm\/"]}]},{"@type":"ImageObject","inLanguage":"fi","@id":"https:\/\/mediagear.ee\/fi\/tuote\/atomos-hdmi-2-0-micro-cable-30-60cm\/#primaryimage","url":"https:\/\/mediagear.ee\/wp-content\/uploads\/2025\/06\/p7566579_855488888_4.jpg","contentUrl":"https:\/\/mediagear.ee\/wp-content\/uploads\/2025\/06\/p7566579_855488888_4.jpg","width":800,"height":534,"caption":"ATOMOS HDMI 2.0 Micro cable, 30\/60cm"},{"@type":"BreadcrumbList","@id":"https:\/\/mediagear.ee\/fi\/tuote\/atomos-hdmi-2-0-micro-cable-30-60cm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mediagear.ee\/fi\/"},{"@type":"ListItem","position":2,"name":"Pro video- ja \u00e4\u00e4nilaitteiden kauppa","item":"https:\/\/mediagear.ee\/fi\/kauppa\/"},{"@type":"ListItem","position":3,"name":"KAAPELIT","item":"https:\/\/mediagear.ee\/fi\/tuote-osasto\/cabling-fi\/"},{"@type":"ListItem","position":4,"name":"HDMI kaapelit","item":"https:\/\/mediagear.ee\/fi\/tuote-osasto\/cabling-fi\/hdmi-cables-fi\/"},{"@type":"ListItem","position":5,"name":"ATOMOS HDMI 2.0 Micro cable, 30\/60cm"}]},{"@type":"WebSite","@id":"https:\/\/mediagear.ee\/fi\/#website","url":"https:\/\/mediagear.ee\/fi\/","name":"MediaGear","description":"Full-service solutions in AV equipment","publisher":{"@id":"https:\/\/mediagear.ee\/fi\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mediagear.ee\/fi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fi"},{"@type":"Organization","@id":"https:\/\/mediagear.ee\/fi\/#organization","name":"Mediagear","url":"https:\/\/mediagear.ee\/fi\/","logo":{"@type":"ImageObject","inLanguage":"fi","@id":"https:\/\/mediagear.ee\/fi\/#\/schema\/logo\/image\/","url":"https:\/\/mediagear.ee\/wp-content\/uploads\/2024\/05\/MediaGear-logo-transp.png","contentUrl":"https:\/\/mediagear.ee\/wp-content\/uploads\/2024\/05\/MediaGear-logo-transp.png","width":600,"height":200,"caption":"Mediagear"},"image":{"@id":"https:\/\/mediagear.ee\/fi\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Mediagear.ee\/","https:\/\/www.instagram.com\/mediagear_ee\/"]}]}},"_links":{"self":[{"href":"https:\/\/mediagear.ee\/fi\/wp-json\/wp\/v2\/product\/280228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mediagear.ee\/fi\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mediagear.ee\/fi\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mediagear.ee\/fi\/wp-json\/wp\/v2\/media\/280229"}],"wp:attachment":[{"href":"https:\/\/mediagear.ee\/fi\/wp-json\/wp\/v2\/media?parent=280228"}],"wp:term":[{"taxonomy":"brand","embeddable":true,"href":"https:\/\/mediagear.ee\/fi\/wp-json\/wp\/v2\/brand?post=280228"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mediagear.ee\/fi\/wp-json\/wp\/v2\/product_cat?post=280228"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mediagear.ee\/fi\/wp-json\/wp\/v2\/product_tag?post=280228"},{"taxonomy":"inventory","embeddable":true,"href":"https:\/\/mediagear.ee\/fi\/wp-json\/wp\/v2\/inventory?post=280228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}